{"id":8825,"date":"2014-06-02T06:15:13","date_gmt":"2014-06-02T05:15:13","guid":{"rendered":"http:\/\/format30.com\/?p=8825"},"modified":"2014-06-18T13:24:38","modified_gmt":"2014-06-18T12:24:38","slug":"mindomo-du-mindmapping-collaboratif-en-ligne-exceptionnel","status":"publish","type":"post","link":"https:\/\/format30.com\/es\/2014\/06\/02\/mindomo-du-mindmapping-collaboratif-en-ligne-exceptionnel\/","title":{"rendered":"Mindomo : du mindmapping collaboratif en ligne exceptionnel"},"content":{"rendered":"<p style=\"text-align:justify;\"><span style=\"color:#000080;\"><strong>J&rsquo;ai test\u00e9 l&rsquo;application de mindmapping collaboratif en ligne (et de bureau) Mindomo. \u00a0 Et j&rsquo;ai \u00e9t\u00e9 agr\u00e9ablement surpris par l&rsquo;\u00e9volution de ce logiciel : une fluidit\u00e9 exceptionnelle et le plein de fonctions plus utiles les unes que les autres !<\/strong><\/span><\/p>\n<p style=\"text-align:justify;\"><span style=\"color:#ff0000;\"><em><strong>Avertissement<\/strong> <\/em><\/span>: <em>une version incompl\u00e8te de cet article a \u00e9t\u00e9 publi\u00e9e par erreur le vendredi 31 mai dernier. \u00a0Je pr\u00e9sente mes excuses \u00e0 tous les lecteurs qui ont re\u00e7u une version tronqu\u00e9e de ce test. \u00a0Voici \u00e0 pr\u00e9sent l&rsquo;article termin\u00e9<\/em>.<\/p>\n<p style=\"text-align:justify;\">Je continue mon exploration des applications et logiciels de mindmapping qui offrent une collaboration en ligne en temps r\u00e9el. \u00a0Et donc, apr\u00e8s <a title=\"MindMaple: mindmapping multiplateforme, collaboratif et gratuit !\" href=\"http:\/\/format30.com\/es\/2013\/03\/18\/mindmaple-mindmapping-multiplateforme-collaboratif-et-gratuit\/\" target=\"_blank\">Mindmaple<\/a>, <a title=\"Test: Mindmeister,  mindmapping multiplateforme et collaboratif\" href=\"http:\/\/format30.com\/es\/2013\/04\/09\/test-mindmeister-mindmapping-multiplateforme-et-collaboratif\/\" target=\"_blank\">Mindmeister<\/a>, <a title=\"WiseMapping : du mindmapping collaboratif, gratuit et open source\" href=\"http:\/\/format30.com\/es\/2014\/02\/18\/wisemapping-du-mindmapping-collaboratif-gratuit-et-open-source\/\" target=\"_blank\">WiseMapping<\/a> et <a title=\"Mind42 : du mindmapping collaboratif gratuit et en temps r\u00e9el\" href=\"http:\/\/format30.com\/es\/2014\/01\/20\/mind42-du-mindmapping-collaboratif-gratuit-et-en-temps-reel\/\" target=\"_blank\">Mind42<\/a>, je teste aujourd&rsquo;hui <a title=\"Inscription gratuite sur Mindomo.com\" href=\"http:\/\/www.mindomo.com\/?join=suAuhx&amp;cmp=0&amp;src=0\" target=\"_blank\">Mindomo<\/a>.<\/p>\n<p style=\"text-align:justify;\">Mindomo est l&rsquo;une des premi\u00e8res applications de mindmapping que j&rsquo;avais essay\u00e9e, il y a un peu plus de 5 ans. \u00a0Et les choses ont bien chang\u00e9 ! \u00a0A l&rsquo;\u00e9poque, l&rsquo;application \u00e9tait assez rudimentaire, m\u00eame si elle proposait d\u00e9j\u00e0 un graphisme attrayant.<\/p>\n<p style=\"text-align:justify;\"><em><strong>Mindomo<\/strong> <\/em>n&rsquo;est plus seulement un logiciel en ligne : vous pouvez t\u00e9l\u00e9charger une version de bureau pour PC, mais aussi <a title=\"Mindomo, logiciel de mindmapping collaboratif et multiplateforme\" href=\"http:\/\/format30.com\/es\/2014\/06\/18\/mindomo-logiciel-de-mindmapping-collaboratif-et-multiplateforme\/\" target=\"_blank\">travailler sur votre smartphone ou tablette Android ainsi que sur iPhone et iPad<\/a>&#8230;<\/p>\n<h2><span style=\"color:#000080;\">Une interface \u00e9l\u00e9gante et une ergonomie sans faille<\/span><\/h2>\n<p style=\"text-align:justify;\">L&rsquo;interface de Mindomo a \u00e9t\u00e9 dessin\u00e9e en <em>Flat design, le<\/em> style minimaliste tr\u00e8s en vogue aujourd&rsquo;hui et tr\u00e8s bien d\u00e9crit dans cet <a href=\"http:\/\/www.heuristiquement.com\/2013\/12\/flat-design.html\" target=\"_blank\">article de mon ami Philippe Boukobza<\/a>.<\/p>\n<p style=\"text-align:justify;\">Il en r\u00e9sulte un ensemble\u00a0 clair, simple et lisible.<\/p>\n<p style=\"text-align:justify;\">L&rsquo;ergonomie de Mindomo a \u00e9t\u00e9 singuli\u00e8rement soign\u00e9e et se r\u00e9v\u00e8le particuli\u00e8rement efficace.\u00a0 Le logiciel propose plusieurs\u00a0 barres d&rsquo;outils en haut, \u00e0 gauche et en bas de l&rsquo;\u00e9cran.\u00a0 Tout est sous la main.<\/p>\n<figure id=\"attachment_9032\" aria-describedby=\"caption-attachment-9032\" style=\"width: 205px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/i0.wp.com\/format30.com\/wp-content\/uploads\/2014\/05\/2014-05-25_15h03_45.png\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"9032\" data-permalink=\"https:\/\/format30.com\/es\/2014\/06\/02\/mindomo-du-mindmapping-collaboratif-en-ligne-exceptionnel\/2014-05-25_15h03_45\/\" data-orig-file=\"https:\/\/i0.wp.com\/format30.com\/wp-content\/uploads\/2014\/05\/2014-05-25_15h03_45.png?fit=329%2C481&amp;ssl=1\" data-orig-size=\"329,481\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"menu de formatage du sujet dans Mindomo\" data-image-description=\"&lt;p&gt;Menu de formatage des sujets dans Mindomo&lt;\/p&gt;\" data-image-caption=\"&lt;p&gt;Menu de format \u00e0 partir d&amp;rsquo;un onglet&lt;\/p&gt;\" data-large-file=\"https:\/\/i0.wp.com\/format30.com\/wp-content\/uploads\/2014\/05\/2014-05-25_15h03_45.png?fit=329%2C481&amp;ssl=1\" class=\"wp-image-9032 size-medium\" src=\"https:\/\/i0.wp.com\/format30.com\/wp-content\/uploads\/2014\/05\/2014-05-25_15h03_45.png?resize=205%2C300\" alt=\"Formatage d'un sujet, de sa couleur, de sa forme, de sa police de caract\u00e8re, de ses connexions et barri\u00e8res dans Mindomo\" width=\"205\" height=\"300\" \/><\/a><figcaption id=\"caption-attachment-9032\" class=\"wp-caption-text\">Menu de format \u00e0 partir d&rsquo;un onglet<\/figcaption><\/figure>\n<p style=\"text-align:justify;\">Mieux, avec la nouvelle version, les\u00a0 menus qui modifient les sujets et leur contenus sont d\u00e9sormais\u00a0 disponibles via un onglet sur les sujets eux-m\u00eames : ce menu permet d&rsquo;ajouter des sous-sujets, un sujet flottant, une liaison avec un autre sujet, d&rsquo;effacer le sujet, de voir l&rsquo;historique de ses modifications, de le couper, de le copier ou de le coller.<\/p>\n<p style=\"text-align:justify;\">C&rsquo;est \u00e9galement \u00e0 partir de cet onglet qu&rsquo;on peut modifier la police de caract\u00e8re, la couleur de cette police, ses attributs, etc.<\/p>\n<p style=\"text-align:justify;\">La couleur et la forme des sujets peuvent \u00e9galement \u00eatre modifi\u00e9es \u00e0 partir d&rsquo;ici, ainsi que le type de connexion des sous-sujets (en mindmap rayonnante ou droite, en organigramme bas ou haut, en arbre logique, etc.).\u00a0 L&rsquo;utilisateur peut aussi r\u00e9gler le format des barri\u00e8res (aussi appel\u00e9es limites ou nuages dans d&rsquo;autres applications).<\/p>\n<p style=\"text-align:justify;\">Bref, un v\u00e9ritable centre de commandes \u00e0 port\u00e9e de main !<\/p>\n<p>&nbsp;<\/p>\n<h2><span style=\"color:#000080;\">Int\u00e9gration : une richesse exceptionnelle !<\/span><\/h2>\n<p>En mati\u00e8re d&rsquo;int\u00e9gration d&rsquo;objets \u00e0 une carte mentale, j&rsquo;ai rarement vu un logiciel aussi complet que <em><strong>Mindomo<\/strong><\/em>.\u00a0 Y compris dans les logiciels de bureau&#8230;<\/p>\n<p>Il est excellent en int\u00e9gration de notes, d&rsquo;hyperliens, d&rsquo;images, de fichiers, etc.\u00a0 Et permet d&rsquo;int\u00e9grer de la vid\u00e9o Youtube qui peut \u00eatre jou\u00e9e sans quitter la carte, y compris en ligne !<\/p>\n<h3><span style=\"color:#000080;\">1. Int\u00e9gration de notes \u00e9crites<\/span><\/h3>\n<p>Mindomo offre un \u00e9diteur de notes assez complet :<\/p>\n<figure id=\"attachment_9036\" aria-describedby=\"caption-attachment-9036\" style=\"width: 300px\" class=\"wp-caption alignright\"><a href=\"https:\/\/i0.wp.com\/format30.com\/wp-content\/uploads\/2014\/05\/editeur-de-notes-mindomo.png\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"9036\" data-permalink=\"https:\/\/format30.com\/es\/2014\/06\/02\/mindomo-du-mindmapping-collaboratif-en-ligne-exceptionnel\/editeur-de-notes-mindomo\/\" data-orig-file=\"https:\/\/i0.wp.com\/format30.com\/wp-content\/uploads\/2014\/05\/editeur-de-notes-mindomo.png?fit=511%2C382&amp;ssl=1\" data-orig-size=\"511,382\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"Editeur de notes Mindomo\" data-image-description=\"&lt;p&gt;Menu Editeur de notes du logiciel de mindmapping mindomo&lt;\/p&gt;\" data-image-caption=\"&lt;p&gt;Editeur de notes de Mindomo&lt;\/p&gt;\" data-large-file=\"https:\/\/i0.wp.com\/format30.com\/wp-content\/uploads\/2014\/05\/editeur-de-notes-mindomo.png?fit=511%2C382&amp;ssl=1\" class=\"wp-image-9036 size-medium\" src=\"https:\/\/i0.wp.com\/format30.com\/wp-content\/uploads\/2014\/05\/editeur-de-notes-mindomo.png?resize=300%2C224\" alt=\"Editeur de notes : permet l'\u00e9dition et l'int\u00e9gration de notes \u00e9crites dans une carte mentale r\u00e9alis\u00e9e avec Mindomo\" width=\"300\" height=\"224\" \/><\/a><figcaption id=\"caption-attachment-9036\" class=\"wp-caption-text\">Editeur de notes Mindomo<\/figcaption><\/figure>\n<ul>\n<li>Type de police<\/li>\n<li>Taille de la police<\/li>\n<li>Enrichissements : gras, italique, soulign\u00e9<\/li>\n<li>Couleur de la police<\/li>\n<li>Alignement : gauche, droit, centr\u00e9, justifier<\/li>\n<li>Corbeille<\/li>\n<\/ul>\n<p>Par contre, on peut regretter les absences suivantes :<\/p>\n<ul>\n<li>Pas de num\u00e9rotation<\/li>\n<li>Pas de liste \u00e0 puces<\/li>\n<li>Pas d&rsquo;int\u00e9gration d&rsquo;images<\/li>\n<\/ul>\n<h3><span style=\"color:#000080;\">\u00a02. Int\u00e9gration d&rsquo;hyperliens<\/span><\/h3>\n<p>Au niveau de l&rsquo;int\u00e9gration des hyperliens aussi, Mindomo se montre d&rsquo;une richesse tr\u00e8s au-dessus de la moyenne des logiciels de mindmapping !\u00a0 Jugez plut\u00f4t :<\/p>\n<h4><span style=\"color:#000080;\">a.Hyperliens vers des sites web<\/span><\/h4>\n<p>Comme beaucoup de logiciels de mindmapping, Mindomo int\u00e8gre des hyperliens vers des sites web.\u00a0 Mais il permet aussi de les int\u00e9grer en tenant compte de deux protocoles :<\/p>\n<ul>\n<li>http\/\/<\/li>\n<li>https\/\/<\/li>\n<\/ul>\n<p>Vous pouvez donc int\u00e9grer des hyperliens s\u00e9curis\u00e9s vers des pages web confidentielles : une bonne chose lorsque vous travaillez en ligne avec vos collaborateurs.<\/p>\n<h4 style=\"text-align:justify;\"><span style=\"color:#000080;\">b. Hyperliens vers un sujet de la m\u00eame carte mentale<\/span><\/h4>\n<p style=\"text-align:justify;\">Vous pouvez lier plusieurs sujets d&rsquo;une m\u00eame carte mentale avec des hyperliens.\u00a0 C&rsquo;est tr\u00e8s int\u00e9ressant lors d&rsquo;une conf\u00e9rence ou lorsque vous manipulez des cartes complexes : vous pouvez passer d&rsquo;une branche \u00e0 l&rsquo;autre tr\u00e8s rapidement de cette fa\u00e7on.<\/p>\n<h4 style=\"text-align:justify;\"><span style=\"color:#000080;\">\u00a0c. Hyperliens vers une autre carte ou une carte secondaire<\/span><\/h4>\n<p style=\"text-align:justify;\">Votre hyperlien peut renvoyer vers une autre carte Mindomo ou vers une carte secondaire : une carte cr\u00e9\u00e9e \u00e0 partir d&rsquo;un sujet de la carte principale et qui vous permet de d\u00e9lester une partie de l&rsquo;information vers une autre carte.<\/p>\n<h4 style=\"text-align:justify;\"><span style=\"color:#000080;\">d. Hyperliens vers FTP<\/span><\/h4>\n<p style=\"text-align:justify;\">Pour les webmasters, il est possible d&rsquo;ins\u00e9rer un lien de type FTP.<\/p>\n<h4 style=\"text-align:justify;\"><span style=\"color:#000080;\">e. Hyperliens vers un fichier<\/span><\/h4>\n<p style=\"text-align:justify;\">Cet hyperlien peut renvoyer vers un fichier sur le disque dur ou d\u00e9j\u00e0 t\u00e9l\u00e9charg\u00e9 sur Mindomo.<\/p>\n<h4 style=\"text-align:justify;\"><span style=\"color:#000080;\">f. Hyperliens vers une adresse e-mail ou vers un num\u00e9ro de t\u00e9l\u00e9phone<\/span><\/h4>\n<p style=\"text-align:justify;\">Last but not least, vous pouvez ins\u00e9r\u00e9r un lien vers une adresse e-mail (mailto:) ou vers un num\u00e9ro de t\u00e9l\u00e9phone (callto:).<\/p>\n<h3 style=\"text-align:justify;\"><span style=\"color:#000080;\">3. Int\u00e9gration d&rsquo;informations de t\u00e2ches<\/span><\/h3>\n<figure id=\"attachment_9057\" aria-describedby=\"caption-attachment-9057\" style=\"width: 409px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/i0.wp.com\/format30.com\/wp-content\/uploads\/2014\/06\/menu-intc3a9gration-de-tc3a2ches.png?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"9057\" data-permalink=\"https:\/\/format30.com\/es\/2014\/06\/02\/mindomo-du-mindmapping-collaboratif-en-ligne-exceptionnel\/menu-integration-de-taches\/\" data-orig-file=\"https:\/\/i0.wp.com\/format30.com\/wp-content\/uploads\/2014\/06\/menu-intc3a9gration-de-tc3a2ches.png?fit=510%2C475&amp;ssl=1\" data-orig-size=\"510,475\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"Menu Int\u00e9gration de t\u00e2ches\" data-image-description=\"&lt;p&gt;Menu int\u00e9gration de taches&lt;\/p&gt;\" data-image-caption=\"&lt;p&gt;Menu Int\u00e9gration des t\u00e2ches&lt;\/p&gt;\" data-large-file=\"https:\/\/i0.wp.com\/format30.com\/wp-content\/uploads\/2014\/06\/menu-intc3a9gration-de-tc3a2ches.png?fit=510%2C475&amp;ssl=1\" class=\"wp-image-9057\" src=\"https:\/\/i0.wp.com\/format30.com\/wp-content\/uploads\/2014\/06\/menu-intc3a9gration-de-tc3a2ches.png?resize=409%2C381\" alt=\"Menu Int\u00e9gration des t\u00e2ches dans le logiciel de mindmapping collaboratif Mindomo pour la gestion de  projets\" width=\"409\" height=\"381\" \/><\/a><figcaption id=\"caption-attachment-9057\" class=\"wp-caption-text\">Menu Int\u00e9gration des t\u00e2ches<\/figcaption><\/figure>\n<p style=\"text-align:justify;\">Mindomo propose un menu de gestion de t\u00e2ches assez complet. \u00a0Il ne se contente pas de cela, puisqu&rsquo;il propose une interface de gestion de projet dont je reparlerai dans un autre article \u00e0 propos de la gestion de projet avec Mindomo.<\/p>\n<p style=\"text-align:justify;\">Pour int\u00e9grer des informations de t\u00e2ches, il faut activer le sujet dans la carte &#8211; en cliquant dessus une seule fois &#8211; et ensuite de cliquer sur l&rsquo;icone en forme de t\u00e2ches v\u00e9rifi\u00e9es \u00e0 gauche (celui qui est dans le p\u00e9rim\u00e8tre jaune).<\/p>\n<p style=\"text-align:justify;\">Vous avez donc le choix entre 9 niveaux de priorit\u00e9. \u00a0Ensuite, compl\u00e9tez le niveau de r\u00e9alisation. \u00a0Donnez la date de d\u00e9marrage de l&rsquo;action et la date d&rsquo;\u00e9ch\u00e9ance.<\/p>\n<p style=\"text-align:justify;\">Vous pouvez aussi estimer la dur\u00e9e de la t\u00e2che en minutes, heures, jours, semaines ou mois.<\/p>\n<p style=\"text-align:justify;\">Assignez une personne responsable. \u00a0Et enfin, vous pouvez demander au programme de calculer automatiquement les priorit\u00e9s de vos t\u00e2ches pour vous aider \u00e0 les prioriser.<\/p>\n<p style=\"text-align:justify;\">Le menu \u00ab\u00a0Param\u00e9trage\u00a0\u00bb permet de d\u00e9finir les param\u00e8tres de votre semaine de travail : nombre de jours par semaine, d&rsquo;heures par jour, etc. \u00a0\u00ab\u00a0Tout enlever\u00a0\u00bb permet d&rsquo;effacer toutes les informations de t\u00e2ches int\u00e9gr\u00e9es dans un sujet.<\/p>\n<p style=\"text-align:justify;\">Comment cela modifie-t-il l&rsquo;apparence du sujet s\u00e9lectionn\u00e9 ? \u00a0Voici le sujet apr\u00e8s l&rsquo;int\u00e9gration des t\u00e2ches :<\/p>\n<figure id=\"attachment_9062\" aria-describedby=\"caption-attachment-9062\" style=\"width: 598px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/format30.com\/wp-content\/uploads\/2014\/06\/informations-de-tc3a2ches-dans-mindomo.png?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"9062\" data-permalink=\"https:\/\/format30.com\/es\/2014\/06\/02\/mindomo-du-mindmapping-collaboratif-en-ligne-exceptionnel\/informations-de-taches-dans-mindomo\/\" data-orig-file=\"https:\/\/i0.wp.com\/format30.com\/wp-content\/uploads\/2014\/06\/informations-de-tc3a2ches-dans-mindomo.png?fit=598%2C314&amp;ssl=1\" data-orig-size=\"598,314\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"Informations de t\u00e2ches dans Mindomo\" data-image-description=\"&lt;p&gt;Int\u00e9gration des informations de t\u00e2ches dans une mindmap mindomo&lt;\/p&gt;\" data-image-caption=\"&lt;p&gt;Le sujet apr\u00e8s int\u00e9gration des t\u00e2ches&lt;\/p&gt;\" data-large-file=\"https:\/\/i0.wp.com\/format30.com\/wp-content\/uploads\/2014\/06\/informations-de-tc3a2ches-dans-mindomo.png?fit=598%2C314&amp;ssl=1\" class=\"size-full wp-image-9062\" src=\"https:\/\/i0.wp.com\/format30.com\/wp-content\/uploads\/2014\/06\/informations-de-tc3a2ches-dans-mindomo.png?resize=598%2C314\" alt=\"Sujet d'une carte Mindomo auquel on a ajout\u00e9 des informations d'int\u00e9gration de t\u00e2ches\" width=\"598\" height=\"314\" \/><\/a><figcaption id=\"caption-attachment-9062\" class=\"wp-caption-text\">Le sujet apr\u00e8s int\u00e9gration des t\u00e2ches<\/figcaption><\/figure>\n<p style=\"text-align:justify;\">Le texte \u00ab\u00a0Int\u00e9gration des t\u00e2ches\u00a0\u00bb est le nom du sujet : j&rsquo;ai test\u00e9 l&rsquo;int\u00e9gration des informations de t\u00e2ches dans un sujet qui en parle : \u00e7a me paraissait logique&#8230;<\/p>\n<p style=\"text-align:justify;\">Le chiffre 1 dans un cercle, sur la deuxi\u00e8me ligne \u00e0 gauche est le niveau de priorit\u00e9 que j&rsquo;ai choisi. \u00a0Le deuxi\u00e8me cercle montre un taux d&rsquo;ach\u00e8vement de 25 %. \u00a0Le calendrier est suivi de la date d&rsquo;ach\u00e8vement, le 11 juin 2014. \u00a0Et enfin, l&rsquo;icone en forme de buste signale que la t\u00e2che m&rsquo;a \u00e9t\u00e9 assign\u00e9e.<\/p>\n<p style=\"text-align:justify;\">Un seul regret : que les ressources ne puissent pas \u00eatre int\u00e9gr\u00e9es dans le sujet comme dans Mindmaple, par exemple. \u00a0Par contre, les ressources &#8211; fichiers Words, Excel, ou autres &#8211; peuvent \u00eatre int\u00e9gr\u00e9s dans un projet avec l&rsquo;interface dont je reparlerai dans un autre article.<\/p>\n<h2 style=\"text-align:justify;\"><span style=\"color:#000080;\">Int\u00e9gration m\u00e9dias : Sons, Images et Vid\u00e9os \u00e0 l&rsquo;honneur<\/span><\/h2>\n<h3 style=\"text-align:justify;\"><span style=\"color:#000080;\">1. Int\u00e9gration d&rsquo;images dans votre carte mentale<\/span><\/h3>\n<p style=\"text-align:justify;\">Mindomo int\u00e8gre des images depuis votre ordinateur, mais aussi via une URL d&rsquo;image int\u00e9gr\u00e9e dans un site web. \u00a0Il les int\u00e8gre aussi depuis d&rsquo;autres sources, comme la biblioth\u00e8que Mindomo, \u00a0Flickr ou \u00ab\u00a0Ma galerie personnelle\u00a0\u00bb, c&rsquo;est-\u00e0-dire des images que vous avez t\u00e9l\u00e9charg\u00e9es pour d&rsquo;autres mindmaps, par exemple.<\/p>\n<p style=\"text-align:justify;\">Il propose \u00e9galement, comme Mindmeister, d&rsquo;int\u00e9grer des images Google. \u00a0Vous pouvez aussi inclure vos images par simple glisser-d\u00e9poser.<\/p>\n<h3 style=\"text-align:justify;\"><span style=\"color:#000080;\">\u00a02. Int\u00e9gration de vid\u00e9os dans votre carte mentale<\/span><\/h3>\n<p style=\"text-align:justify;\">Mindomo permet d&rsquo;int\u00e9grer dans la carte mentale des vid\u00e9os : elles sont int\u00e9gr\u00e9es \u00e0 un sujet et peuvent \u00eatre \u00ab\u00a0jou\u00e9es\u00a0\u00bb dans la carte, lors d&rsquo;une pr\u00e9sentation ou de l&rsquo;int\u00e9gration de la carte dans un site web, par exemple.<\/p>\n<p style=\"text-align:justify;\">Ces vid\u00e9os peuvent provenir de trois sources :<\/p>\n<ol style=\"text-align:justify;\">\n<li>\u00a0Youtube<\/li>\n<li>\u00a0Vim\u00e9o<\/li>\n<li>de votre ordinateur<\/li>\n<\/ol>\n<p style=\"text-align:justify;\">Pour les deux premi\u00e8res, il suffit d&rsquo;inclure leur URL et Mindomo se charge de les inclure dans la carte. \u00a0Pour celles qui figurent sur votre ordinateur, vous pouvez les glisser-d\u00e9poser ou naviguer sur votre disque et s\u00e9lectionner le fichier \u00e0 t\u00e9l\u00e9charger.<\/p>\n<h3><span style=\"color:#000080;\">3. Int\u00e9gration de sons dans la carte mentale<\/span><\/h3>\n<p style=\"text-align:justify;\">Mindomo vous permet \u00e9galement d&rsquo;int\u00e9grer des \u00e9lements sonores dans une carte mentale.\u00a0 Ces fichiers audio peuvent provenir de diverses sources :<\/p>\n<ul style=\"text-align:justify;\">\n<li>en ligne avec l&rsquo;URL<\/li>\n<li>biblioth\u00e8que<\/li>\n<li>note audio<\/li>\n<\/ul>\n<p style=\"text-align:justify;\">Pour les fichiers en ligne, il suffit d&rsquo;entrer leur URL.\u00a0 Par exemple, l&rsquo;adresse d&rsquo;un fichier de type Soundcloud.\u00a0 Dans ce cas, l&rsquo;icone Soundcloud s&rsquo;affiche tandis que le fichier est ouvert \u00e0 l&rsquo;ext\u00e9rieur de la carte.<\/p>\n<p style=\"text-align:justify;\">Le fichier peut \u00e9galement provenir de notre propre biblioth\u00e8que &#8211; c&rsquo;est-\u00e0-dire des fichiers pr\u00e9alablement t\u00e9l\u00e9charg\u00e9s dans votre compte Mindomo.\u00a0 Ou vous pouvez les t\u00e9l\u00e9charger au moment o\u00f9 vous r\u00e9alisez la carte.<\/p>\n<p style=\"text-align:justify;\">Et enfin, vous pouvez enregistrer directement des notes audio dans la carte.\u00a0 L&rsquo;image ci-dessous illustre trois fa\u00e7ons d&rsquo;int\u00e9grer un fichier son dans Mindomo : la premi\u00e8re est une icone Soundcloud dont on a simplement entr\u00e9 l&rsquo;URL.\u00a0 La deuxi\u00e8me est un fichier de type MP3 t\u00e9l\u00e9charg\u00e9 (num\u00e9ro 2) et la troisi\u00e8me (num\u00e9ro 2) est une note audio enregristr\u00e9e dans la carte.\u00a0 Les icones des deux derniers fichiers sont identiques : il faut cliquer sur le bouton Start pour lancer la lecture.\u00a0 On peut r\u00e9gler le volume sonore \u00e0 partir de la carte elle-m\u00eame&#8230;<\/p>\n<figure id=\"attachment_9072\" aria-describedby=\"caption-attachment-9072\" style=\"width: 282px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/format30.com\/wp-content\/uploads\/2014\/06\/fichiers-audio.png?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"9072\" data-permalink=\"https:\/\/format30.com\/es\/2014\/06\/02\/mindomo-du-mindmapping-collaboratif-en-ligne-exceptionnel\/fichiers-audio\/\" data-orig-file=\"https:\/\/i0.wp.com\/format30.com\/wp-content\/uploads\/2014\/06\/fichiers-audio.png?fit=282%2C251&amp;ssl=1\" data-orig-size=\"282,251\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"Fichiers audio\" data-image-description=\"&lt;p&gt;Trois types de fichiers audio dans une carte mentale Mindomo&lt;\/p&gt;\" data-image-caption=\"&lt;p&gt;Fichiers audio dans une carte Mindomo&lt;\/p&gt;\" data-large-file=\"https:\/\/i0.wp.com\/format30.com\/wp-content\/uploads\/2014\/06\/fichiers-audio.png?fit=282%2C251&amp;ssl=1\" class=\"size-full wp-image-9072\" src=\"https:\/\/i0.wp.com\/format30.com\/wp-content\/uploads\/2014\/06\/fichiers-audio.png?resize=282%2C251\" alt=\"Plusieurs types de fichiers audio dans une mindmap mindomo : une adresse d'enregistrement soundcloud, un fichier mp3 et une note audio\" width=\"282\" height=\"251\" \/><\/a><figcaption id=\"caption-attachment-9072\" class=\"wp-caption-text\">Fichiers audio dans une carte Mindomo<\/figcaption><\/figure>\n<h2><span style=\"color:#000080;\">\u00a04. Int\u00e9gration de documents<\/span><\/h2>\n<p style=\"text-align:justify;\">Il est possible d&rsquo;int\u00e9grer de nombreux formats de documents dans une carte Mindomo.\u00a0 J&rsquo;ai par exemple int\u00e9gr\u00e9 un document de type epub (livre num\u00e9rique) par simple glisser-d\u00e9poser (drag &amp; drop) depuis ma collection de livres num\u00e9riques dans un sujet de ma carte.<\/p>\n<p><span class=\"embed-youtube\" style=\"text-align:center; display: block;\"><iframe loading=\"lazy\" class=\"youtube-player\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/C1oRTy282Ck?version=3&enablejsapi=1#038;rel=1&#038;showsearch=0&#038;showinfo=1&#038;iv_load_policy=1&#038;fs=1&#038;hl=es-ES&#038;autohide=2&#038;wmode=transparent\" allowfullscreen=\"true\" style=\"border:0;\" sandbox=\"allow-scripts allow-same-origin allow-popups allow-presentation allow-popups-to-escape-sandbox\"><\/iframe><\/span><\/p>\n<p>Vous pouvez aussi rechercher des fichiers avec l&rsquo;explorateur Windows ou lier un fichier d\u00e9j\u00e0 t\u00e9l\u00e9charg\u00e9 dans votre biblioth\u00e8que Mindomo&#8230;<\/p>\n<h2><span style=\"color:#000080;\">Collaboration : une fluidit\u00e9 exceptionnelle !<\/span><\/h2>\n<p style=\"text-align:justify;\">\u00a0De toutes les fonctionnalit\u00e9s de Mindomo, celle qui m&rsquo;a le plus impressionn\u00e9 jusqu&rsquo;\u00e0 pr\u00e9sent, c&rsquo;est la collaboration en ligne.<\/p>\n<p style=\"text-align:justify;\">Le chat permet d&rsquo;\u00e9changer en ligne en temps r\u00e9el pendant que diff\u00e9rentes personnes collaborent sur la m\u00eame carte.<\/p>\n<p style=\"text-align:justify;\">\u00a0Les modifications effectu\u00e9es sur la carte sont visibles en temps r\u00e9el, synchrone. \u00a0La modification\u00a0 des sujets et des divers objets sur la carte s&rsquo;op\u00e8re de mani\u00e8re tr\u00e8s fluide et tr\u00e8s rapide.<\/p>\n<figure id=\"attachment_9067\" aria-describedby=\"caption-attachment-9067\" style=\"width: 563px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/format30.com\/wp-content\/uploads\/2014\/06\/chat-sur-mindomo.png?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"9067\" data-permalink=\"https:\/\/format30.com\/es\/2014\/06\/02\/mindomo-du-mindmapping-collaboratif-en-ligne-exceptionnel\/chat-sur-mindomo\/\" data-orig-file=\"https:\/\/i0.wp.com\/format30.com\/wp-content\/uploads\/2014\/06\/chat-sur-mindomo.png?fit=563%2C633&amp;ssl=1\" data-orig-size=\"563,633\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"Chat sur Mindomo\" data-image-description=\"&lt;p&gt;Chat pendant une session synchrone sur une m\u00eame mindmap&lt;\/p&gt;\" data-image-caption=\"&lt;p&gt;Chat sur Mindomo&lt;\/p&gt;\" data-large-file=\"https:\/\/i0.wp.com\/format30.com\/wp-content\/uploads\/2014\/06\/chat-sur-mindomo.png?fit=563%2C633&amp;ssl=1\" class=\"size-full wp-image-9067\" src=\"https:\/\/i0.wp.com\/format30.com\/wp-content\/uploads\/2014\/06\/chat-sur-mindomo.png?resize=563%2C633\" alt=\"Chat sur Mindomo pendant une collaboration en temps r\u00e9el (synchrone) sur une m\u00eame carte mentale\" width=\"563\" height=\"633\" \/><\/a><figcaption id=\"caption-attachment-9067\" class=\"wp-caption-text\">Chat sur Mindomo<\/figcaption><\/figure>\n<p>Le chat s&rsquo;active en cliquant sur l&rsquo;icone en forme de bulle de BD (phylact\u00e8re) en bas \u00e0 droite de l&rsquo;\u00e9cran.<\/p>\n<h2><span style=\"color:#000080;\">\u00a0R\u00e9visions, historique et bookmarks<\/span><\/h2>\n<p style=\"text-align:justify;\">Pour un logiciel qui autorise la collaboration en temps r\u00e9el (synchrone), les r\u00e9visions et l&rsquo;historique d&rsquo;une cartes sont essentielles.\u00a0 En effet, comment savoir sinon quelles modifications vos coll\u00e8gues ont apport\u00e9es \u00e0\u00a0 la carte commune ?<\/p>\n<p style=\"text-align:justify;\">Mindomo pr\u00e9voit des commentaires et un historique de chaque carte.<\/p>\n<h3 style=\"text-align:justify;\"><span style=\"color:#000080;\">1. Les commentaires<\/span><\/h3>\n<p style=\"text-align:justify;\">Les commentaires sont ins\u00e9r\u00e9s via un petit \u00e9diteur de texte.\u00a0 Il suffit de taper le commentaire dans la zone pr\u00e9vue et de taper \u00ab\u00a0Enter\u00a0\u00bb.\u00a0 Il est int\u00e9gr\u00e9 dans le sujet et une icone marque l&#8217;emplacement du commentaire.<\/p>\n<p style=\"text-align:justify;\">Des icones de type \u00ab\u00a0Like\u00a0\u00bb et \u00ab\u00a0Dislike\u00a0\u00bb permettent d&rsquo;afficher visuellement son avis sur un sujet ou le contenu d&rsquo;une carte&#8230;<\/p>\n<figure id=\"attachment_9079\" aria-describedby=\"caption-attachment-9079\" style=\"width: 700px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/format30.com\/wp-content\/uploads\/2014\/06\/commentaires-dans-mindomo.png?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"9079\" data-permalink=\"https:\/\/format30.com\/es\/2014\/06\/02\/mindomo-du-mindmapping-collaboratif-en-ligne-exceptionnel\/commentaires-dans-mindomo\/\" data-orig-file=\"https:\/\/i0.wp.com\/format30.com\/wp-content\/uploads\/2014\/06\/commentaires-dans-mindomo.png?fit=1414%2C616&amp;ssl=1\" data-orig-size=\"1414,616\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"Commentaires dans Mindomo\" data-image-description=\"&lt;p&gt;Commentaires dans une mindmap Mindomo&lt;\/p&gt;\" data-image-caption=\"&lt;p&gt;Commentaires dans Mindomo&lt;\/p&gt;\" data-large-file=\"https:\/\/i0.wp.com\/format30.com\/wp-content\/uploads\/2014\/06\/commentaires-dans-mindomo.png?fit=1024%2C446&amp;ssl=1\" class=\"wp-image-9079 size-large\" src=\"https:\/\/i0.wp.com\/format30.com\/wp-content\/uploads\/2014\/06\/commentaires-dans-mindomo.png?resize=700%2C304\" alt=\"Comment r\u00e9diger des commentaires dans une carte mentale mindomo : \u00e9diteur de texte et icone sp\u00e9cifique de commentaire\" width=\"700\" height=\"304\" \/><\/a><figcaption id=\"caption-attachment-9079\" class=\"wp-caption-text\">Commentaires dans Mindomo<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<h3><span style=\"color:#000080;\">2. Les r\u00e9visions<\/span><\/h3>\n<p style=\"text-align:justify;\">Mindomo offre des r\u00e9visions compl\u00e8tes de l&rsquo;historique d&rsquo;une carte mentale.\u00a0 Cliquez sur <em>Outils<\/em> et ensuite, sur <em>View changes for maps<\/em> (non, cette partie n&rsquo;est pas traduite !) et Mindomo vous affiche les changements pour plusieurs p\u00e9riodes possibles :<\/p>\n<figure id=\"attachment_9081\" aria-describedby=\"caption-attachment-9081\" style=\"width: 700px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/format30.com\/wp-content\/uploads\/2014\/06\/historique-dune-mindmap.png?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"9081\" data-permalink=\"https:\/\/format30.com\/es\/2014\/06\/02\/mindomo-du-mindmapping-collaboratif-en-ligne-exceptionnel\/historique-dune-mindmap\/\" data-orig-file=\"https:\/\/i0.wp.com\/format30.com\/wp-content\/uploads\/2014\/06\/historique-dune-mindmap.png?fit=785%2C587&amp;ssl=1\" data-orig-size=\"785,587\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"Historique d&amp;rsquo;une mindmap\" data-image-description=\"&lt;p&gt;Fen\u00eatre des r\u00e9visions d&amp;rsquo;une mindmap dans Mindomo&lt;\/p&gt;\" data-image-caption=\"&lt;p&gt;Changements d&amp;rsquo;une mindmap&lt;\/p&gt;\" data-large-file=\"https:\/\/i0.wp.com\/format30.com\/wp-content\/uploads\/2014\/06\/historique-dune-mindmap.png?fit=785%2C587&amp;ssl=1\" class=\"size-large wp-image-9081\" src=\"https:\/\/i0.wp.com\/format30.com\/wp-content\/uploads\/2014\/06\/historique-dune-mindmap.png?resize=700%2C523\" alt=\"R\u00e9vision : Mindomo affiche l'historique des modification d'une carte mentale r\u00e9alis\u00e9e avec le logiciel de mindmapping  avec plusieurs p\u00e9riodes possibles\" width=\"700\" height=\"523\" \/><\/a><figcaption id=\"caption-attachment-9081\" class=\"wp-caption-text\">Changements d&rsquo;une mindmap<\/figcaption><\/figure>\n<h3 style=\"text-align:justify;\"><span style=\"color:#000080;\">3. Bookmarks\u00a0 ou liens favoris<\/span><\/h3>\n<p style=\"text-align:justify;\">Mindomo propose aussi d&rsquo;utiliser les bookmarks (ou vos liens favoris) pour les int\u00e9grer dans une carte mentale : j&rsquo;en ai fait l&rsquo;essai que j&rsquo;ai enregistr\u00e9 dans cette vid\u00e9o :<\/p>\n<p><span class=\"embed-youtube\" style=\"text-align:center; display: block;\"><iframe loading=\"lazy\" class=\"youtube-player\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/TssUMKhiEtY?version=3&enablejsapi=1#038;rel=1&#038;showsearch=0&#038;showinfo=1&#038;iv_load_policy=1&#038;fs=1&#038;hl=es-ES&#038;autohide=2&#038;wmode=transparent\" allowfullscreen=\"true\" style=\"border:0;\" sandbox=\"allow-scripts allow-same-origin allow-popups allow-presentation allow-popups-to-escape-sandbox\"><\/iframe><\/span><\/p>\n<h2 style=\"text-align:justify;\"><span style=\"color:#000080;\">Importations et exportations : tout simplement \u00e9tonnant !<\/span><\/h2>\n<p style=\"text-align:justify;\">Mindomo affiche un potentiel d&rsquo;importations et d&rsquo;exportations peu commun.\u00a0 Jugez par vous-m\u00eame :<\/p>\n<h3 style=\"text-align:justify;\"><span style=\"color:#000080;\">1. Importations<\/span><\/h3>\n<figure id=\"attachment_9083\" aria-describedby=\"caption-attachment-9083\" style=\"width: 616px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/format30.com\/wp-content\/uploads\/2014\/06\/imports-mindaps-dans-mindomo.png?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"9083\" data-permalink=\"https:\/\/format30.com\/es\/2014\/06\/02\/mindomo-du-mindmapping-collaboratif-en-ligne-exceptionnel\/imports-mindaps-dans-mindomo\/\" data-orig-file=\"https:\/\/i0.wp.com\/format30.com\/wp-content\/uploads\/2014\/06\/imports-mindaps-dans-mindomo.png?fit=616%2C349&amp;ssl=1\" data-orig-size=\"616,349\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"Imports mindaps dans Mindomo\" data-image-description=\"&lt;p&gt;Formats d&amp;rsquo;importation dans Mindomo \u00e0 partir de votre PC, de Dropbox ou de Google Drive&lt;\/p&gt;\" data-image-caption=\"&lt;p&gt;Importations dans Mindomo&lt;\/p&gt;\" data-large-file=\"https:\/\/i0.wp.com\/format30.com\/wp-content\/uploads\/2014\/06\/imports-mindaps-dans-mindomo.png?fit=616%2C349&amp;ssl=1\" class=\"size-full wp-image-9083\" src=\"https:\/\/i0.wp.com\/format30.com\/wp-content\/uploads\/2014\/06\/imports-mindaps-dans-mindomo.png?resize=616%2C349\" alt=\"Fichiers importables dans Mindomo depuis Dropbox, Google Drive ou votre ordinateur : un nombre impressionnant de logiciels de mindmapping\" width=\"616\" height=\"349\" \/><\/a><figcaption id=\"caption-attachment-9083\" class=\"wp-caption-text\">Importations dans Mindomo<\/figcaption><\/figure>\n<p style=\"text-align:justify;\">Les importations peuvent se faire via votre ordinateur, Google Drive ou Dropbox.<\/p>\n<p style=\"text-align:justify;\">Vous pouvez importer des mindmaps de pas moins de 6 formats de logiciels de mindmapping plus des fichiers textes et le standard d&rsquo;\u00e9change OPML.<\/p>\n<p>&nbsp;<\/p>\n<h3><span style=\"color:#000080;\">2. Exportations<\/span><\/h3>\n<p style=\"text-align:justify;\">Mais c&rsquo;est sans doute au niveau des exportations que le logiciel de mindmapping se distingue.\u00a0 J&rsquo;ai utilis\u00e9 la version gratuite pour vous montrer quelles \u00e9taient les fonctionnalit\u00e9s r\u00e9serv\u00e9es aux abonn\u00e9s payants :<\/p>\n<figure id=\"attachment_9086\" aria-describedby=\"caption-attachment-9086\" style=\"width: 700px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/i0.wp.com\/format30.com\/wp-content\/uploads\/2014\/06\/menu-exports-de-mindomo.png?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"9086\" data-permalink=\"https:\/\/format30.com\/es\/2014\/06\/02\/mindomo-du-mindmapping-collaboratif-en-ligne-exceptionnel\/menu-exports-de-mindomo\/\" data-orig-file=\"https:\/\/i0.wp.com\/format30.com\/wp-content\/uploads\/2014\/06\/menu-exports-de-mindomo.png?fit=1116%2C711&amp;ssl=1\" data-orig-size=\"1116,711\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"menu exports de Mindomo\" data-image-description=\"&lt;p&gt;Exportations depuis une carte mentale Mindomo&lt;\/p&gt;\" data-image-caption=\"&lt;p&gt;Exportations depuis Mindomo&lt;\/p&gt;\" data-large-file=\"https:\/\/i0.wp.com\/format30.com\/wp-content\/uploads\/2014\/06\/menu-exports-de-mindomo.png?fit=1024%2C652&amp;ssl=1\" class=\"size-large wp-image-9086\" src=\"https:\/\/i0.wp.com\/format30.com\/wp-content\/uploads\/2014\/06\/menu-exports-de-mindomo.png?resize=700%2C445\" alt=\"Formats d'exportations depuis le logiciel de mindmapping Mindomo vers les applications de la suite Microsoft Office et d'autres standards\" width=\"700\" height=\"445\" \/><\/a><figcaption id=\"caption-attachment-9086\" class=\"wp-caption-text\">Exportations depuis Mindomo<\/figcaption><\/figure>\n<p>La plupart des exportations sont r\u00e9serv\u00e9es aux abonn\u00e9s payants.\u00a0 Mais il n&rsquo;en reste pas moins que la liste est impressionnante.\u00a0 Je n&rsquo;ai pas encore eu l&rsquo;occasion de les tester tous !<\/p>\n<p>Pour les entreprises, le fait de pouvoir exporter les t\u00e2ches sous forme de diagramme de Gantt est \u00e9videmment appr\u00e9ciable, tout comme le lien possible avec Microsoft Project.<\/p>\n<h2><span style=\"color:#000080;\">En conclusion : un logiciel de mindmapping d&rsquo;une richesse exceptionnelle !<\/span><\/h2>\n<p style=\"text-align:justify;\">Apr\u00e8s un mois et demi de tests et d&rsquo;essais divers, je n&rsquo;ai pas eu l&rsquo;occasion de faire le tour de toutes les fonctionnalit\u00e9s de Mindomo.\u00a0 Je voudrais encore tester la gestion de projet \u00e0 plusieurs avec collaboration en temps r\u00e9el sur des t\u00e2ches pr\u00e9cises avec \u00e9changes de ressources, etc.<\/p>\n<p style=\"text-align:justify;\">Je vous parlerai de Mindomo pour Android et IOS dans un prochain billet ainsi que d&rsquo;autres fonctionnalit\u00e9s.<\/p>\n<p style=\"text-align:justify;\">Mais d\u00e9j\u00e0, je peux conclure sans arri\u00e8re-pens\u00e9e qu&rsquo;il s&rsquo;agit d&rsquo;une des meilleures applications de mindmapping que j&rsquo;ai pu tester jusqu&rsquo;ici, que ce soit en ligne ou en version de bureau.<\/p>\n<p style=\"text-align:justify;\">Le lien : <a href=\"http:\/\/www.mindomo.com\/?join=suAuhx&amp;cmp=0&amp;src=0\">Mindomo<\/a>.<\/p>\n<p style=\"text-align:center;\"><span style=\"color:#000080;\"><strong>Vous avez aim\u00e9 cet article ?\u00a0 Inscrivez-vous \u00e0\u00a0<span style=\"color:#3366ff;\"><a title=\"Inscription newsletter Marco Bertolini - Conseil et formation\" href=\"http:\/\/eepurl.com\/tOqA1\"><span style=\"color:#3366ff;\">ma newsletter<\/span><\/a><\/span>\u00a0et ne ratez plus aucun article ou \u00e9v\u00e9n\u00e9ment !<\/strong><\/span><\/p>","protected":false},"excerpt":{"rendered":"<p>J&rsquo;ai test\u00e9 l&rsquo;application de mindmapping collaboratif en ligne (et de bureau) Mindomo. \u00a0 Et j&rsquo;ai \u00e9t\u00e9 agr\u00e9ablement surpris par l&rsquo;\u00e9volution de ce logiciel : une fluidit\u00e9 exceptionnelle et le plein [&hellip;]<\/p>\n","protected":false},"author":7601135,"featured_media":9079,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_coblocks_attr":"","_coblocks_dimensions":"","_coblocks_responsive_height":"","_coblocks_accordion_ie_support":"","_monsterinsights_skip_tracking":false,"_EventAllDay":false,"_EventTimezone":"","_EventStartDate":"","_EventEndDate":"","_EventStartDateUTC":"","_EventEndDateUTC":"","_EventShowMap":false,"_EventShowMapLink":false,"_EventURL":"","_EventCost":"","_EventCostDescription":"","_EventCurrencySymbol":"","_EventCurrencyCode":"","_EventCurrencyPosition":"","_EventDateTimeSeparator":"","_EventTimeRangeSeparator":"","_EventOrganizerID":[],"_EventVenueID":[],"_OrganizerEmail":"","_OrganizerPhone":"","_OrganizerWebsite":"","_VenueAddress":"","_VenueCity":"","_VenueCountry":"","_VenueProvince":"","_VenueState":"","_VenueZip":"","_VenuePhone":"","_VenueURL":"","_VenueStateProvince":"","_VenueLat":"","_VenueLng":"","_VenueShowMap":false,"_VenueShowMapLink":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_wpcom_ai_launchpad_first_post":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"{title}\n\n{excerpt}\n\n{url}","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false,"jetpack_post_was_ever_published":false},"categories":[9857,873081,8],"tags":[1119466,5505528,238881316,138200042,114245,775357425,775357479,775357451,13518085,412],"class_list":["post-8825","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-logiciels","category-mindomo","category-test","tag-carte-heuristique","tag-cartes-mentales","tag-collaboration-en-temps-reel","tag-logiciel-mindmapping","tag-mindmap","tag-mindmapping","tag-mindmapping-collaboratif","tag-mindomo","tag-synchrone","tag-video"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mindomo : du mindmapping collaboratif en ligne exceptionnel - Formation 3.0<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/format30.com\/es\/2014\/06\/02\/mindomo-du-mindmapping-collaboratif-en-ligne-exceptionnel\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mindomo : du mindmapping collaboratif en ligne exceptionnel - Formation 3.0\" \/>\n<meta property=\"og:description\" content=\"J&rsquo;ai test\u00e9 l&rsquo;application de mindmapping collaboratif en ligne (et de bureau) Mindomo. \u00a0 Et j&rsquo;ai \u00e9t\u00e9 agr\u00e9ablement surpris par l&rsquo;\u00e9volution de ce logiciel : une fluidit\u00e9 exceptionnelle et le plein [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/format30.com\/es\/2014\/06\/02\/mindomo-du-mindmapping-collaboratif-en-ligne-exceptionnel\/\" \/>\n<meta property=\"og:site_name\" content=\"Formation 3.0\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Formation3.0\" \/>\n<meta property=\"article:published_time\" content=\"2014-06-02T05:15:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2014-06-18T12:24:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/format30.com\/wp-content\/uploads\/2014\/06\/commentaires-dans-mindomo.png?fit=1414%2C616&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1414\" \/>\n\t<meta property=\"og:image:height\" content=\"616\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Marco Bertolini\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Formation3_0\" \/>\n<meta name=\"twitter:site\" content=\"@Formation3_0\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marco Bertolini\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"12 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/format30.com\\\/2014\\\/06\\\/02\\\/mindomo-du-mindmapping-collaboratif-en-ligne-exceptionnel\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/format30.com\\\/2014\\\/06\\\/02\\\/mindomo-du-mindmapping-collaboratif-en-ligne-exceptionnel\\\/\"},\"author\":{\"name\":\"Marco Bertolini\",\"@id\":\"https:\\\/\\\/format30.com\\\/#\\\/schema\\\/person\\\/9c8a29bf75bd97a3627fb4d531320bf2\"},\"headline\":\"Mindomo : du mindmapping collaboratif en ligne exceptionnel\",\"datePublished\":\"2014-06-02T05:15:13+00:00\",\"dateModified\":\"2014-06-18T12:24:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/format30.com\\\/2014\\\/06\\\/02\\\/mindomo-du-mindmapping-collaboratif-en-ligne-exceptionnel\\\/\"},\"wordCount\":2521,\"commentCount\":58,\"publisher\":{\"@id\":\"https:\\\/\\\/format30.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/format30.com\\\/2014\\\/06\\\/02\\\/mindomo-du-mindmapping-collaboratif-en-ligne-exceptionnel\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/format30.com\\\/wp-content\\\/uploads\\\/2014\\\/06\\\/commentaires-dans-mindomo.png?fit=1414%2C616&ssl=1\",\"keywords\":[\"carte heuristique\",\"cartes mentales\",\"collaboration en temps r\u00e9el\",\"logiciel mindmapping\",\"mindmap\",\"mindmapping\",\"mindmapping collaboratif\",\"Mindomo\",\"synchrone\",\"vid\u00e9o\"],\"articleSection\":[\"Logiciels\",\"Mindomo\",\"Test\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/format30.com\\\/2014\\\/06\\\/02\\\/mindomo-du-mindmapping-collaboratif-en-ligne-exceptionnel\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/format30.com\\\/2014\\\/06\\\/02\\\/mindomo-du-mindmapping-collaboratif-en-ligne-exceptionnel\\\/\",\"url\":\"https:\\\/\\\/format30.com\\\/2014\\\/06\\\/02\\\/mindomo-du-mindmapping-collaboratif-en-ligne-exceptionnel\\\/\",\"name\":\"Mindomo : du mindmapping collaboratif en ligne exceptionnel - Formation 3.0\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/format30.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/format30.com\\\/2014\\\/06\\\/02\\\/mindomo-du-mindmapping-collaboratif-en-ligne-exceptionnel\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/format30.com\\\/2014\\\/06\\\/02\\\/mindomo-du-mindmapping-collaboratif-en-ligne-exceptionnel\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/format30.com\\\/wp-content\\\/uploads\\\/2014\\\/06\\\/commentaires-dans-mindomo.png?fit=1414%2C616&ssl=1\",\"datePublished\":\"2014-06-02T05:15:13+00:00\",\"dateModified\":\"2014-06-18T12:24:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/format30.com\\\/2014\\\/06\\\/02\\\/mindomo-du-mindmapping-collaboratif-en-ligne-exceptionnel\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/format30.com\\\/2014\\\/06\\\/02\\\/mindomo-du-mindmapping-collaboratif-en-ligne-exceptionnel\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/format30.com\\\/2014\\\/06\\\/02\\\/mindomo-du-mindmapping-collaboratif-en-ligne-exceptionnel\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/format30.com\\\/wp-content\\\/uploads\\\/2014\\\/06\\\/commentaires-dans-mindomo.png?fit=1414%2C616&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/format30.com\\\/wp-content\\\/uploads\\\/2014\\\/06\\\/commentaires-dans-mindomo.png?fit=1414%2C616&ssl=1\",\"width\":1414,\"height\":616,\"caption\":\"Commentaires dans Mindomo\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/format30.com\\\/2014\\\/06\\\/02\\\/mindomo-du-mindmapping-collaboratif-en-ligne-exceptionnel\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/format30.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mindomo : du mindmapping collaboratif en ligne exceptionnel\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/format30.com\\\/#website\",\"url\":\"https:\\\/\\\/format30.com\\\/\",\"name\":\"Formation 3.0\",\"description\":\"Formation 3.0 est un site d\u00e9di\u00e9 \u00e0 la formation, \u00e0 l&#039;\u00e9ducation, \u00e0 l&#039;emploi des nouvelles technologies dans l&#039;enseignement et \u00e0 la pens\u00e9e visuelle.\",\"publisher\":{\"@id\":\"https:\\\/\\\/format30.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/format30.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/format30.com\\\/#organization\",\"name\":\"Formation 3.0\",\"url\":\"https:\\\/\\\/format30.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/format30.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/format30.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/6a1a3-cropped-logo-f30-2023.jpg?fit=512%2C512&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/format30.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/6a1a3-cropped-logo-f30-2023.jpg?fit=512%2C512&ssl=1\",\"width\":512,\"height\":512,\"caption\":\"Formation 3.0\"},\"image\":{\"@id\":\"https:\\\/\\\/format30.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Formation3.0\",\"https:\\\/\\\/x.com\\\/Formation3_0\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/formation-3-0\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/format30.com\\\/#\\\/schema\\\/person\\\/9c8a29bf75bd97a3627fb4d531320bf2\",\"name\":\"Marco Bertolini\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/755a2d19e08e5921fafc9312381678cb3dd80f323b22b8d9d7c88f18254e3165?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/755a2d19e08e5921fafc9312381678cb3dd80f323b22b8d9d7c88f18254e3165?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/755a2d19e08e5921fafc9312381678cb3dd80f323b22b8d9d7c88f18254e3165?s=96&r=g\",\"caption\":\"Marco Bertolini\"},\"description\":\"Formateur et concepteur p\u00e9dagogique, je propose des formations num\u00e9riques en pr\u00e9sentiel enrichi, en formation hybride (pr\u00e9sentiel enrichi et cours en ligne) et en formation 100 % en ligne (e-learning ou FOAD).\",\"url\":\"https:\\\/\\\/format30.com\\\/es\\\/author\\\/marcobertolini\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mindomo : du mindmapping collaboratif en ligne exceptionnel - Formation 3.0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/format30.com\/es\/2014\/06\/02\/mindomo-du-mindmapping-collaboratif-en-ligne-exceptionnel\/","og_locale":"es_ES","og_type":"article","og_title":"Mindomo : du mindmapping collaboratif en ligne exceptionnel - Formation 3.0","og_description":"J&rsquo;ai test\u00e9 l&rsquo;application de mindmapping collaboratif en ligne (et de bureau) Mindomo. \u00a0 Et j&rsquo;ai \u00e9t\u00e9 agr\u00e9ablement surpris par l&rsquo;\u00e9volution de ce logiciel : une fluidit\u00e9 exceptionnelle et le plein [&hellip;]","og_url":"https:\/\/format30.com\/es\/2014\/06\/02\/mindomo-du-mindmapping-collaboratif-en-ligne-exceptionnel\/","og_site_name":"Formation 3.0","article_publisher":"https:\/\/www.facebook.com\/Formation3.0","article_published_time":"2014-06-02T05:15:13+00:00","article_modified_time":"2014-06-18T12:24:38+00:00","og_image":[{"width":1414,"height":616,"url":"https:\/\/i0.wp.com\/format30.com\/wp-content\/uploads\/2014\/06\/commentaires-dans-mindomo.png?fit=1414%2C616&ssl=1","type":"image\/png"}],"author":"Marco Bertolini","twitter_card":"summary_large_image","twitter_creator":"@Formation3_0","twitter_site":"@Formation3_0","twitter_misc":{"Escrito por":"Marco Bertolini","Tiempo de lectura":"12 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/format30.com\/2014\/06\/02\/mindomo-du-mindmapping-collaboratif-en-ligne-exceptionnel\/#article","isPartOf":{"@id":"https:\/\/format30.com\/2014\/06\/02\/mindomo-du-mindmapping-collaboratif-en-ligne-exceptionnel\/"},"author":{"name":"Marco Bertolini","@id":"https:\/\/format30.com\/#\/schema\/person\/9c8a29bf75bd97a3627fb4d531320bf2"},"headline":"Mindomo : du mindmapping collaboratif en ligne exceptionnel","datePublished":"2014-06-02T05:15:13+00:00","dateModified":"2014-06-18T12:24:38+00:00","mainEntityOfPage":{"@id":"https:\/\/format30.com\/2014\/06\/02\/mindomo-du-mindmapping-collaboratif-en-ligne-exceptionnel\/"},"wordCount":2521,"commentCount":58,"publisher":{"@id":"https:\/\/format30.com\/#organization"},"image":{"@id":"https:\/\/format30.com\/2014\/06\/02\/mindomo-du-mindmapping-collaboratif-en-ligne-exceptionnel\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/format30.com\/wp-content\/uploads\/2014\/06\/commentaires-dans-mindomo.png?fit=1414%2C616&ssl=1","keywords":["carte heuristique","cartes mentales","collaboration en temps r\u00e9el","logiciel mindmapping","mindmap","mindmapping","mindmapping collaboratif","Mindomo","synchrone","vid\u00e9o"],"articleSection":["Logiciels","Mindomo","Test"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/format30.com\/2014\/06\/02\/mindomo-du-mindmapping-collaboratif-en-ligne-exceptionnel\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/format30.com\/2014\/06\/02\/mindomo-du-mindmapping-collaboratif-en-ligne-exceptionnel\/","url":"https:\/\/format30.com\/2014\/06\/02\/mindomo-du-mindmapping-collaboratif-en-ligne-exceptionnel\/","name":"Mindomo : du mindmapping collaboratif en ligne exceptionnel - Formation 3.0","isPartOf":{"@id":"https:\/\/format30.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/format30.com\/2014\/06\/02\/mindomo-du-mindmapping-collaboratif-en-ligne-exceptionnel\/#primaryimage"},"image":{"@id":"https:\/\/format30.com\/2014\/06\/02\/mindomo-du-mindmapping-collaboratif-en-ligne-exceptionnel\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/format30.com\/wp-content\/uploads\/2014\/06\/commentaires-dans-mindomo.png?fit=1414%2C616&ssl=1","datePublished":"2014-06-02T05:15:13+00:00","dateModified":"2014-06-18T12:24:38+00:00","breadcrumb":{"@id":"https:\/\/format30.com\/2014\/06\/02\/mindomo-du-mindmapping-collaboratif-en-ligne-exceptionnel\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/format30.com\/2014\/06\/02\/mindomo-du-mindmapping-collaboratif-en-ligne-exceptionnel\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/format30.com\/2014\/06\/02\/mindomo-du-mindmapping-collaboratif-en-ligne-exceptionnel\/#primaryimage","url":"https:\/\/i0.wp.com\/format30.com\/wp-content\/uploads\/2014\/06\/commentaires-dans-mindomo.png?fit=1414%2C616&ssl=1","contentUrl":"https:\/\/i0.wp.com\/format30.com\/wp-content\/uploads\/2014\/06\/commentaires-dans-mindomo.png?fit=1414%2C616&ssl=1","width":1414,"height":616,"caption":"Commentaires dans Mindomo"},{"@type":"BreadcrumbList","@id":"https:\/\/format30.com\/2014\/06\/02\/mindomo-du-mindmapping-collaboratif-en-ligne-exceptionnel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/format30.com\/"},{"@type":"ListItem","position":2,"name":"Mindomo : du mindmapping collaboratif en ligne exceptionnel"}]},{"@type":"WebSite","@id":"https:\/\/format30.com\/#website","url":"https:\/\/format30.com\/","name":"Formation 3.0","description":"Formaci\u00f3n 3.0 es un sitio web dedicado a la formaci\u00f3n, la educaci\u00f3n, el uso de las nuevas tecnolog\u00edas en la ense\u00f1anza y el pensamiento visual.","publisher":{"@id":"https:\/\/format30.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/format30.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/format30.com\/#organization","name":"Formation 3.0","url":"https:\/\/format30.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/format30.com\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/format30.com\/wp-content\/uploads\/2024\/09\/6a1a3-cropped-logo-f30-2023.jpg?fit=512%2C512&ssl=1","contentUrl":"https:\/\/i0.wp.com\/format30.com\/wp-content\/uploads\/2024\/09\/6a1a3-cropped-logo-f30-2023.jpg?fit=512%2C512&ssl=1","width":512,"height":512,"caption":"Formation 3.0"},"image":{"@id":"https:\/\/format30.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Formation3.0","https:\/\/x.com\/Formation3_0","https:\/\/www.linkedin.com\/company\/formation-3-0\/"]},{"@type":"Person","@id":"https:\/\/format30.com\/#\/schema\/person\/9c8a29bf75bd97a3627fb4d531320bf2","name":"Marco Bertolini","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/755a2d19e08e5921fafc9312381678cb3dd80f323b22b8d9d7c88f18254e3165?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/755a2d19e08e5921fafc9312381678cb3dd80f323b22b8d9d7c88f18254e3165?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/755a2d19e08e5921fafc9312381678cb3dd80f323b22b8d9d7c88f18254e3165?s=96&r=g","caption":"Marco Bertolini"},"description":"Como formador y dise\u00f1ador pedag\u00f3gico, ofrezco cursos de formaci\u00f3n digital presenciales enriquecidos, cursos h\u00edbridos (presenciales enriquecidos y cursos en l\u00ednea) y cursos 100 % en l\u00ednea (e-learning o FOAD).","url":"https:\/\/format30.com\/es\/author\/marcobertolini\/"}]}},"jetpack_publicize_connections":[],"jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pK9xl-2il","jetpack-related-posts":[],"amp_enabled":true,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/format30.com\/wp-content\/uploads\/2014\/06\/commentaires-dans-mindomo.png?fit=1414%2C616&ssl=1","_links":{"self":[{"href":"https:\/\/format30.com\/es\/wp-json\/wp\/v2\/posts\/8825","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/format30.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/format30.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/format30.com\/es\/wp-json\/wp\/v2\/users\/7601135"}],"replies":[{"embeddable":true,"href":"https:\/\/format30.com\/es\/wp-json\/wp\/v2\/comments?post=8825"}],"version-history":[{"count":25,"href":"https:\/\/format30.com\/es\/wp-json\/wp\/v2\/posts\/8825\/revisions"}],"predecessor-version":[{"id":9219,"href":"https:\/\/format30.com\/es\/wp-json\/wp\/v2\/posts\/8825\/revisions\/9219"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/format30.com\/es\/wp-json\/wp\/v2\/media\/9079"}],"wp:attachment":[{"href":"https:\/\/format30.com\/es\/wp-json\/wp\/v2\/media?parent=8825"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/format30.com\/es\/wp-json\/wp\/v2\/categories?post=8825"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/format30.com\/es\/wp-json\/wp\/v2\/tags?post=8825"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}